{"id":2078,"date":"2021-11-10T18:08:49","date_gmt":"2021-11-10T17:08:49","guid":{"rendered":"https:\/\/new.menshen.com\/products\/chemical-closure-10698-1\/"},"modified":"2021-11-10T18:41:40","modified_gmt":"2021-11-10T17:41:40","slug":"chemical-closure-10698-1","status":"publish","type":"product","link":"https:\/\/menshen.com\/fr\/produits\/chemical-closure-10698-1\/","title":{"rendered":"Chemical Closure 10698..1"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2310,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[73,94,101,80],"product_tag":[],"class_list":["post-2078","product","type-product","status-publish","has-post-thumbnail","product_cat-bottle-container","product_cat-chemical-closure","product_cat-chemicals","product_cat-screw-version","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","sold-individually","shipping-taxable","product-type-simple"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/menshen.com\/wp-content\/uploads\/2021\/11\/menshen_chemical-closure-10698-1.jpg",900,600,false],"thumbnail":["https:\/\/menshen.com\/wp-content\/uploads\/2021\/11\/menshen_chemical-closure-10698-1-150x150.jpg",150,150,true],"medium":["https:\/\/menshen.com\/wp-content\/uploads\/2021\/11\/menshen_chemical-closure-10698-1-300x200.jpg",300,200,true],"medium_large":["https:\/\/menshen.com\/wp-content\/uploads\/2021\/11\/menshen_chemical-closure-10698-1-768x512.jpg",768,512,true],"large":["https:\/\/menshen.com\/wp-content\/uploads\/2021\/11\/menshen_chemical-closure-10698-1.jpg",900,600,false],"1536x1536":["https:\/\/menshen.com\/wp-content\/uploads\/2021\/11\/menshen_chemical-closure-10698-1.jpg",900,600,false],"2048x2048":["https:\/\/menshen.com\/wp-content\/uploads\/2021\/11\/menshen_chemical-closure-10698-1.jpg",900,600,false],"woocommerce_thumbnail":["https:\/\/menshen.com\/wp-content\/uploads\/2021\/11\/menshen_chemical-closure-10698-1-300x200.jpg",300,200,true],"woocommerce_single":["https:\/\/menshen.com\/wp-content\/uploads\/2021\/11\/menshen_chemical-closure-10698-1-600x400.jpg",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/menshen.com\/wp-content\/uploads\/2021\/11\/menshen_chemical-closure-10698-1-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"Robert He\u00dfe","author_link":"https:\/\/menshen.com\/fr\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/menshen.com\/fr\/wp-json\/wp\/v2\/product\/2078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/menshen.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/menshen.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/menshen.com\/fr\/wp-json\/wp\/v2\/media\/2310"}],"wp:attachment":[{"href":"https:\/\/menshen.com\/fr\/wp-json\/wp\/v2\/media?parent=2078"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/menshen.com\/fr\/wp-json\/wp\/v2\/product_brand?post=2078"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/menshen.com\/fr\/wp-json\/wp\/v2\/product_cat?post=2078"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/menshen.com\/fr\/wp-json\/wp\/v2\/product_tag?post=2078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}